{"id":20332,"date":"2024-12-20T07:36:54","date_gmt":"2024-12-20T07:36:54","guid":{"rendered":"https:\/\/autoservizitempesta.it\/_wp_\/?page_id=20332"},"modified":"2024-12-20T08:01:14","modified_gmt":"2024-12-20T08:01:14","slug":"privacy-policy-2","status":"publish","type":"page","link":"https:\/\/www.autoservizitempesta.it\/_wp_\/privacy-policy-2\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text css=&#8221;&#8221;]<\/p>\n<h2>Chi siamo<\/h2>\n<p>L\u2019indirizzo del nostro sito web \u00e8: www.autoservizi.it<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Commenti<\/strong><br \/>\nQuando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all\u2019indirizzo IP del visitatore e la stringa dello user agent del browser per facilitare il rilevamento dello spam.<\/p>\n<p>Una stringa anonimizzata creata a partire dal tuo indirizzo email (altrimenti detta hash) pu\u00f2 essere fornita al servizio Gravatar per vedere se lo stai usando. La privacy policy del servizio Gravatar \u00e8 disponibile qui: https:\/\/automattic.com\/privacy\/. Dopo l\u2019approvazione del tuo commento, la tua immagine del profilo \u00e8 visibile al pubblico nel contesto del tuo commento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cookie<\/strong><\/p>\n<p>Titolare del trattamento<br \/>\nTempesta Autoservizi | Via De Rossi, 65-65\/A 70121 Bari \u2013 Italy | P.Iva 06744110724 | Tel +39.080.5219172 | info@autoservizitempesta.it<\/p>\n<p>Ai sensi dell\u2019art. 13 D.Lgs. 30.6.2003 n. 196 (in seguito, \u201cCodice Privacy\u201d) e dell\u2019art. 13 Regolamento UE n. 2016\/679 (in seguito, \u201cGDPR\u201d) i Suoi dati saranno trattati con le modalit\u00e0 e per le finalit\u00e0 seguenti:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Oggetto del Trattamento<\/strong><br \/>\nIl Titolare tratta i dati personali, identificativi (ad esempio, nome, cognome, ragione sociale, indirizzo, telefono, e-mail, riferimenti bancari e di pagamento) in seguito, \u201cdati personali\u201d o anche \u201cdati\u201d) da Lei comunicati.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Finalit\u00e0 del trattamento<\/strong><br \/>\nI Suoi dati personali sono trattati:<br \/>\nA) senza il Suo consenso espresso (art. 24 lett. a), b), c) Codice Privacy e art. 6 lett. b), e) GDPR), per le seguenti Finalit\u00e0 di Servizio:<br \/>\n\u2013 concludere i contratti per i servizi del Titolare;<br \/>\n\u2013 adempiere agli obblighi precontrattuali, contrattuali e fiscali derivanti da rapporti con Lei in essere;<br \/>\n\u2013 adempiere agli obblighi previsti dalla legge, da un regolamento, dalla normativa comunitaria o da un ordine dell\u2019Autorit\u00e0 (come ad esempio in materia di antiriciclaggio);<br \/>\n\u2013 esercitare i diritti del Titolare, ad esempio il diritto di difesa in giudizio;<br \/>\nB) Solo previo Suo specifico e distinto consenso (artt. 23 e 130 Codice Privacy e art. 7 GDPR), per le seguenti finalit\u00e0 di marketing:<br \/>\n\u2013 inviarLe via e-mail, posta e\/o sms e\/o contatti telefonici, newsletter, comunicazioni commerciali e\/o materiale pubblicitario su prodotti o servizi offerti dal Titolare e rilevazione del grado di soddisfazione sulla qualit\u00e0 dei servizi;<br \/>\n\u2013 inviarLe via e-mail, posta e\/o sms e\/o contatti telefonici comunicazioni commerciali e\/o promozionali di soggetti terzi (ad esempio, business partner, compagnie assicurative, altre societ\u00e0 del gruppo).<br \/>\nLe segnaliamo che se siete gi\u00e0 nostri clienti, potremo inviarLe comunicazioni commerciali relative a servizi e prodotti del Titolare analoghi a quelli di cui ha gi\u00e0 usufruito, salvo Suo dissenso (art. 130 c. 4 Codice Privacy).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Modalit\u00e0 di trattamento<\/strong><br \/>\nIl trattamento dei Suoi dati personali \u00e8 realizzato per mezzo delle operazioni indicate all\u2019art. 4 Codice Privacy e all\u2019art. 4 n. 2) GDPR e precisamente: raccolta, registrazione, organizzazione, conservazione, consultazione, elaborazione, modificazione, selezione, estrazione, raffronto, utilizzo, interconnessione, blocco, comunicazione, cancellazione e distruzione dei dati. I Suoi dati personali sono sottoposti a trattamento sia cartaceo che elettronico e\/o automatizzato.<br \/>\nIl Titolare tratter\u00e0 i dati personali per il tempo necessario per adempiere alle finalit\u00e0 di cui sopra e comunque per non oltre 10 anni dalla cessazione del rapporto per le Finalit\u00e0 di Servizio e per non oltre 10 anni dalla raccolta dei dati per le Finalit\u00e0 di Marketing.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Accesso ai dati<\/strong><br \/>\nI Suoi dati potranno essere resi accessibili per le finalit\u00e0 di cui all\u2019art. 2.A) e 2.B):<br \/>\n\u2013 a dipendenti e collaboratori del Titolare o delle societ\u00e0 connesse in Italia e all\u2019estero, nella loro qualit\u00e0 di incaricati e\/o responsabili interni del trattamento e\/o amministratori di sistema;<br \/>\n\u2013 a societ\u00e0 terze o altri soggetti (a titolo indicativo, istituti di credito, studi professionali, consulenti, societ\u00e0 di assicurazione per la prestazione di servizi assicurativi, etc.) che svolgono attivit\u00e0 in outsourcing per conto del Titolare, nella loro qualit\u00e0 di responsabili esterni del trattamento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Comunicazione dei dati<\/strong><br \/>\nSenza la necessit\u00e0 di un espresso consenso (ex art. 24 lett. a), b), d) Codice Privacy e art. 6 lett. b) e c) GDPR), il Titolare potr\u00e0 comunicare i Suoi dati per le finalit\u00e0 di cui all\u2019art. 2.A) a Organismi di vigilanza (quali IVASS), Autorit\u00e0 giudiziarie, a societ\u00e0 di assicurazione per la prestazione di servizi assicurativi, nonch\u00e9 a quei soggetti ai quali la comunicazione sia obbligatoria per legge per l\u2019espletamento delle finalit\u00e0 dette. Detti soggetti tratteranno i dati nella loro qualit\u00e0 di autonomi titolari del trattamento.<br \/>\nI Suoi dati non saranno diffusi.<\/p>\n<p><strong>Trasferimento dati<\/strong><br \/>\nI dati personali sono conservati:<br \/>\n\u2013 se hai compilato un modulo cartaceo presso la sede del Titolare (Italia);<br \/>\n\u2013 se hai compilato un modulo online presso i server di Supernova srl (Italia) oppure Google Inc. (USA)<br \/>\nResta in ogni caso inteso che il Titolare, ove si rendesse necessario, avr\u00e0 facolt\u00e0 di spostare i server in UE o anche extra-UE. Il Titolare assicura sin d\u2019ora che il trasferimento dei dati avverr\u00e0 in conformit\u00e0 alle disposizioni di legge applicabili, previa stipula delle clausole contrattuali standard previste dalla Commissione Europea.<\/p>\n<p>Natura del conferimento dei dati e conseguenze del rifiuto di rispondere<br \/>\nIl conferimento dei dati per le finalit\u00e0 di cui all\u2019art. 2.A) \u00e8 obbligatorio. In loro assenza, non potremo garantirLe i Servizi dell\u2019art. 2.A). Il conferimento dei dati per le finalit\u00e0 di cui all\u2019art. 2.B) \u00e8 invece facoltativo. Pu\u00f2 quindi decidere di non conferire alcun dato o di negare successivamente la possibilit\u00e0 di trattare dati gi\u00e0 forniti: in tal caso, non potr\u00e0 ricevere newsletter, comunicazioni commerciali e materiale pubblicitario inerenti ai Servizi offerti dal Titolare. Continuer\u00e0 comunque ad avere diritto ai Servizi di cui all\u2019art. 2.A).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Diritti dell\u2019interessato<\/strong><br \/>\nNella Sua qualit\u00e0 di interessato, ha i diritti di cui all\u2019art. 7 Codice Privacy e art. 15 GDPR e precisamente i diritti di:<\/p>\n<p>ottenere la conferma dell\u2019esistenza o meno di dati personali che La riguardano, anche se non ancora registrati, e la loro comunicazione in forma intelligibile;<br \/>\nottenere l\u2019indicazione: a) dell\u2019origine dei dati personali; b) delle finalit\u00e0 e modalit\u00e0 del trattamento; c) della logica applicata in caso di trattamento effettuato con l\u2019ausilio di strumenti elettronici; d) degli estremi identificativi del titolare, dei responsabili e del rappresentante designato ai sensi dell\u2019art. 5, comma 2 Codice Privacy e art. 3, comma 1, GDPR; e) dei soggetti o delle categorie di soggetti ai quali i dati personali possono essere comunicati o che possono venirne a conoscenza in qualit\u00e0 di rappresentante designato nel territorio dello Stato, di responsabili o incaricati;<br \/>\nottenere: a) l\u2019aggiornamento, la rettificazione ovvero, quando vi ha interesse, l\u2019integrazione dei dati; b) la cancellazione, la trasformazione in forma anonima o il blocco dei dati trattati in violazione di legge, compresi quelli di cui non \u00e8 necessaria la conservazione in relazione agli scopi per i quali i dati sono stati raccolti o successivamente trattati; c) l\u2019attestazione che le operazioni di cui alle lettere a) e b) sono state portate a conoscenza, anche per quanto riguarda il loro contenuto, di coloro ai quali i dati sono stati comunicati o diffusi, eccettuato il caso in cui tale adempimento si rivela impossibile o comporta un impiego di mezzi manifestamente sproporzionato rispetto al diritto tutelato;<br \/>\nopporsi, in tutto o in parte: a) per motivi legittimi al trattamento dei dati personali che La riguardano, ancorch\u00e9 pertinenti allo scopo della raccolta; b) al trattamento di dati personali che La riguardano a fini di invio di materiale pubblicitario o di vendita diretta o per il compimento di ricerche di mercato o di comunicazione commerciale, mediante l\u2019uso di sistemi automatizzati di chiamata senza l\u2019intervento di un operatore mediante e-mail e\/o mediante modalit\u00e0 di marketing tradizionali mediante telefono e\/o posta cartacea. Si fa presente che il diritto di opposizione dell\u2019interessato, esposto al precedente punto b), per finalit\u00e0 di marketing diretto mediante modalit\u00e0 automatizzate si estende a quelle tradizionali e che comunque resta salva la possibilit\u00e0 per l\u2019interessato di esercitare il diritto di opposizione anche solo in parte. Pertanto, l\u2019interessato pu\u00f2 decidere di ricevere solo comunicazioni mediante modalit\u00e0 tradizionali ovvero solo comunicazioni automatizzate oppure nessuna delle due tipologie di comunicazione.<br \/>\nOve applicabili, ha altres\u00ec i diritti di cui agli artt. 16-21 GDPR (Diritto di rettifica, diritto all\u2019oblio, diritto di limitazione di trattamento, diritto alla portabilit\u00e0 dei dati, diritto di opposizione), nonch\u00e9 il diritto di reclamo all\u2019Autorit\u00e0 Garante.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Modalit\u00e0 di esercizio dei diritti<\/strong><br \/>\nPotr\u00e0 in qualsiasi momento esercitare i diritti inviando:<br \/>\n\u2013 una raccomandata a.r. a Tempesta Autoservizi | Via De Rossi, 65-65\/A 70121 Bari \u2013 Italy<br \/>\n\u2013 una e-mail all\u2019indirizzo info@autoservizitempesta.it<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Titolare, responsabile e incaricati<\/strong><br \/>\nIl Titolare del trattamento \u00e8 Tempesta Autoservizi | Via De Rossi, 65-65\/A 70121 Bari<br \/>\nL\u2019elenco aggiornato dei responsabili e degli incaricati al trattamento \u00e8 custodito presso la sede legale del Titolare del trattamento.<\/p>\n<p>&nbsp;<\/p>\n<p>Questa Applicazione raccoglie alcuni Dati Personali dei propri Utenti.<\/p>\n<p>Cookie<br \/>\nPiccola porzione di dati conservata all\u2019interno del dispositivo dell\u2019Utente.<br \/>\nEmail<br \/>\nFornisce accesso all\u2019indirizzo email primario dell\u2019utente<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tipologie di Dati raccolti<\/strong><br \/>\nFra i Dati Personali raccolti da questa Applicazione, in modo autonomo o tramite terze parti, ci sono: Cookie, Dati di utilizzo, Email, Password, Nome, Cognome e Email.<br \/>\nAltri Dati Personali raccolti potrebbero essere indicati in altre sezioni di questa privacy policy o mediante testi informativi visualizzati contestualmente alla raccolta dei Dati stessi.<br \/>\nI Dati Personali possono essere inseriti volontariamente dall\u2019Utente, oppure raccolti in modo automatico durante l\u2019uso di questa Applicazione.<br \/>\nL\u2019eventuale utilizzo di Cookie \u2013 o di altri strumenti di tracciamento \u2013 da parte di questa Applicazione o dei titolari dei servizi terzi utilizzati da questa Applicazione, ove non diversamente precisato, ha la finalit\u00e0 di identificare l\u2019Utente e registrare le relative preferenze per finalit\u00e0 strettamente legate all\u2019erogazione del servizio richiesto dall\u2019Utente.<br \/>\nIl mancato conferimento da parte dell\u2019Utente di alcuni Dati Personali potrebbe impedire a questa Applicazione di erogare i propri servizi.<br \/>\nL\u2019Utente si assume la responsabilit\u00e0 dei Dati Personali di terzi pubblicati o condivisi mediante questa Applicazione e garantisce di avere il diritto di comunicarli o diffonderli, liberando il Titolare da qualsiasi responsabilit\u00e0 verso terzi.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Finalit\u00e0 del Trattamento dei Dati raccolti<\/strong><br \/>\nI Dati dell\u2019Utente sono raccolti per consentire al Titolare di fornire i propri servizi, cos\u00ec come per le seguenti finalit\u00e0: Statistica, Marketing.<br \/>\nLe tipologie di Dati Personali utilizzati per ciascuna finalit\u00e0 sono indicati nelle sezioni specifiche di questo documento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cookie policy<\/strong><br \/>\nI Cookie sono costituiti da porzioni di codice installate all\u2019interno del browser che assistono il Titolare nell\u2019erogazione del servizio in base alle finalit\u00e0 descritte. Alcune delle finalit\u00e0 di installazione dei Cookie potrebbero, inoltre, necessitare del consenso dell\u2019Utente.<\/p>\n<p>&nbsp;<\/p>\n<p>Cookie tecnici e di statistica aggregata<br \/>\n\u2013 Attivit\u00e0 strettamente necessarie al funzionamento<br \/>\nQuesta Applicazione utilizza Cookie per salvare la sessione dell\u2019Utente e per svolgere altre attivit\u00e0 strettamente necessarie al funzionamento dello stesso, ad esempio in relazione alla distribuzione del traffico.<br \/>\n\u2013 Attivit\u00e0 di salvataggio delle preferenze, ottimizzazione e statistica<br \/>\nQuesta Applicazione utilizza Cookie per salvare le preferenze di navigazione ed ottimizzare l\u2019esperienza di navigazione dell\u2019Utente. Fra questi Cookie rientrano, ad esempio, quelli per impostare la lingua e la valuta o per la gestione di statistiche da parte del Titolare del sito.<br \/>\n\u2013 Come posso controllare l\u2019installazione di Cookie?<br \/>\nIn aggiunta a quanto indicato in questo documento, l\u2019Utente pu\u00f2 gestire le preferenze relative ai Cookie direttamente all\u2019interno del proprio browser ed impedire \u2013 ad esempio \u2013 che terze parti possano installarne. Tramite le preferenze del browser \u00e8 inoltre possibile eliminare i Cookie installati in passato, incluso il Cookie in cui venga eventualmente salvato il consenso all\u2019installazione di Cookie da parte di questo sito. \u00c8 importante notare che disabilitando tutti i Cookie, il funzionamento di questo sito potrebbe essere compromesso. L\u2019Utente pu\u00f2 trovare informazioni su come gestire i Cookie nel suo browser ai seguenti indirizzi: Google Chrome, Mozilla Firefox, Apple Safari, Microsoft Edge and Microsoft Windows Explorer.<br \/>\nIn caso di servizi erogati da terze parti, l\u2019Utente pu\u00f2 inoltre esercitare il proprio diritto ad opporsi al tracciamento informandosi tramite la privacy policy della terza parte, tramite il link di opt out se esplicitamente fornito o contattando direttamente la stessa.<br \/>\nFermo restando quanto precede, il Titolare informa che l\u2019Utente pu\u00f2 avvalersi di Your Online Choises. Attraverso tale servizio \u00e8 possibile gestire le preferenze di tracciamento della maggior parte degli strumenti pubblicitari. Il Titolare, pertanto, consiglia agli Utenti di utilizzare tale risorsa in aggiunta alle informazioni fornite dal presente documento.<br \/>\nDal momento che l\u2019installazione di Cookie e di altri sistemi di tracciamento operata da terze parti tramite i servizi utilizzati all\u2019interno di questa Applicazione non pu\u00f2 essere tecnicamente controllata dal Titolare, ogni riferimento specifico a Cookie e sistemi di tracciamento installati da terze parti \u00e8 da considerarsi indicativo. Per ottenere informazioni complete, consulta la privacy policy degli eventuali servizi terzi elencati in questo documento.<br \/>\nVista l\u2019oggettiva complessit\u00e0 legata all\u2019identificazione delle tecnologie basate sui Cookie ed alla loro integrazione molto stretta con il funzionamento del web, l\u2019Utente \u00e8 invitato a contattare il Titolare qualora volesse ricevere qualunque approfondimento relativo all\u2019utilizzo dei Cookie stessi e ad eventuali utilizzi degli stessi \u2013 ad esempio ad opera di terzi \u2013 effettuati tramite questo sito.<\/p>\n<p><strong>Dettagli sull\u2019utilizzo dei cookie e sul trattamento dei Dati Personali<\/strong><br \/>\nI Dati Personali sono raccolti per le seguenti finalit\u00e0 ed utilizzando i seguenti servizi elencati di seguito. Tali servizi potrebbero non richiedere il consenso dell\u2019Utente o potrebbero essere gestiti direttamente dal Titolare \u2013 a seconda di quanto descritto \u2013 senza l\u2019ausilio di terzi.<br \/>\nQualora fra gli strumenti indicati in seguito fossero presenti servizi gestiti da terzi, questi potrebbero \u2013 in aggiunta a quanto specificato ed anche all\u2019insaputa del Titolare \u2013 compiere attivit\u00e0 di tracciamento dell\u2019Utente. Per informazioni dettagliate in merito, si consiglia di consultare le privacy policy dei servizi elencati.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Applicazioni Sociali<\/strong><br \/>\nQuesti servizi permettono al sito web di attingere ai dati del tuo profilo sui social networks, e di effettuare interazioni al tuo post. Questi servizi non sono attivati automaticamente, ma richiedono un\u2019autorizzazione esplicita da parte dell\u2019utente.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Accesso all\u2019account Facebook<\/strong><br \/>\nQuesto servizio permette a questa Applicazione di connettersi con l\u2019account dell\u2019Utente sul social network Facebook, fornito da Facebook, Inc. \u2013 Privacy Policy<\/p>\n<p><strong>Interazione con social network e piattaforme esterne<\/strong><br \/>\nQuesti servizi permettono di effettuare interazioni con i social network, o con altre piattaforme esterne, direttamente dalle pagine dell\u2019Applicazione. Le interazioni e le informazioni acquisite da questa Applicazione sono in ogni caso soggette alle impostazioni privacy dell\u2019Utente relative ad ogni social network.<br \/>\nNel caso in cui sia installato un servizio di interazione con i social network (Pulsanti e Widget), \u00e8 possibile che, anche nel caso gli Utenti non utilizzino il servizio, lo stesso raccolga dati di traffico relativi alle pagine in cui \u00e8 installato.<br \/>\n\u2013 Pulsante Mi Piace e widget sociali di Facebook<br \/>\nsono servizi di interazione con il social network Facebook, forniti da Facebook, Inc. \u2013 Privacy Policy<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Monitoraggio dell\u2019infrastruttura<\/strong><br \/>\nQuesti servizi permettono a questa Applicazione di monitorare l\u2019utilizzo ed il comportamento di componenti della stessa, per consentirne il miglioramento delle prestazioni e delle funzionalit\u00e0, la manutenzione o la risoluzione di problemi.<br \/>\nI Dati Personali trattati dipendono dalle caratteristiche e della modalit\u00e0 d\u2019implementazione di questi servizi, che per loro natura filtrano l\u2019attivit\u00e0 di questa Applicazione.<br \/>\n\u2013 Uptime Robot<br \/>\nUptime Robot \u00e8 un servizio di monitoraggio fornito da Uptime Robot Service Provider Ltd \u2013 Privacy Policy<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Statistica<\/strong><br \/>\nI servizi contenuti nella presente sezione permettono al Titolare del Trattamento di monitorare e analizzare i dati di traffico e servono a tener traccia del comportamento dell\u2019Utente.<br \/>\n\u2013 Google Analytics (Google)<br \/>\nGoogle Analytics \u00e8 un servizio di analisi web fornito da Google Inc. (\u201cGoogle\u201d). Google utilizza i Dati Personali raccolti allo scopo di tracciare ed esaminare l\u2019utilizzo di questa Applicazione, compilare report e condividerli con gli altri servizi sviluppati da Google.<br \/>\nGoogle potrebbe utilizzare i Dati Personali per contestualizzare e personalizzare gli annunci del proprio network pubblicitario.<br \/>\nPrivacy Policy \u2013 Opt Out<\/p>\n<p><strong>Log di sistema e manutenzione<\/strong><br \/>\nPer necessit\u00e0 legate al funzionamento ed alla manutenzione, questa Applicazione e gli eventuali servizi terzi da essa utilizzati potrebbero raccogliere Log di sistema, ossia file che registrano le interazioni e che possono contenere anche Dati Personali, quali l\u2019indirizzo IP Utente.<\/p>\n<p><strong>Cookie Necessari<\/strong><br \/>\nI cookie necessari aiutano a contribuire a rendere fruibile un sito web abilitando le funzioni di base come la navigazione della pagina e l\u2019accesso alle aree protette del sito. Il sito web non pu\u00f2 funzionare correttamente senza questi cookie.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cookie Statistici<\/strong><br \/>\nI cookie statistici aiutano i proprietari del sito web a capire come i visitatori interagiscono con i siti raccogliendo e trasmettendo informazioni in forma anonima.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contenuto incorporato da altri siti web<\/strong><br \/>\nGli articoli su questo sito possono includere contenuti incorporati (ad esempio video, immagini, articoli, ecc.). I contenuti incorporati da altri siti web si comportano esattamente allo stesso modo come se il visitatore avesse visitato l\u2019altro sito web.<\/p>\n<p>Questi siti web possono raccogliere dati su di te, usare cookie, integrare ulteriori tracciamenti di terze parti e monitorare l\u2019interazione con essi, incluso il tracciamento della tua interazione con il contenuto incorporato se hai un account e sei connesso a quei siti web.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Con chi condividiamo i tuoi dati<\/strong><br \/>\nSe richiedi una reimpostazione della password, il tuo indirizzo IP verr\u00e0 incluso nell\u2019email di reimpostazione.<\/p>\n<p>&nbsp;<\/p>\n<p>Per quanto tempo conserviamo i tuoi dati<br \/>\nSe lasci un commento, il commento e i relativi metadati vengono conservati a tempo indeterminato. \u00c8 cos\u00ec che possiamo riconoscere e approvare automaticamente eventuali commenti successivi invece di tenerli in una coda di moderazione.<\/p>\n<p>Per gli utenti che si registrano sul nostro sito web (se presenti), memorizziamo anche le informazioni personali che forniscono nel loro profilo utente. Tutti gli utenti possono vedere, modificare o eliminare le loro informazioni personali in qualsiasi momento (eccetto il loro nome utente che non possono cambiare). Gli amministratori del sito web possono anche vedere e modificare queste informazioni.[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_empty_space height=&#8221;60&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text css=&#8221;&#8221;] Chi siamo L\u2019indirizzo del nostro sito web \u00e8: www.autoservizi.it &nbsp; Commenti Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all\u2019indirizzo IP del visitatore e la stringa dello user&#8230;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-20332","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy Policy - Tempesta Autoservizi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Tempesta Autoservizi\" \/>\n<meta property=\"og:description\" content=\"[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text css=&#8221;&#8221;] Chi siamo L\u2019indirizzo del nostro sito web \u00e8: www.autoservizi.it &nbsp; Commenti Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all\u2019indirizzo IP del visitatore e la stringa dello user...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tempesta Autoservizi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autoservizitempesta\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T08:01:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/\",\"url\":\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/\",\"name\":\"Privacy Policy - Tempesta Autoservizi\",\"isPartOf\":{\"@id\":\"https:\/\/www.autoservizitempesta.it\/#website\"},\"datePublished\":\"2024-12-20T07:36:54+00:00\",\"dateModified\":\"2024-12-20T08:01:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.autoservizitempesta.it\/_wp_\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.autoservizitempesta.it\/#website\",\"url\":\"https:\/\/www.autoservizitempesta.it\/\",\"name\":\"Tempesta Autoservizi\",\"description\":\"Viaggiare sereni\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.autoservizitempesta.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Tempesta Autoservizi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy Policy - Tempesta Autoservizi","og_description":"[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column][vc_column_text css=&#8221;&#8221;] Chi siamo L\u2019indirizzo del nostro sito web \u00e8: www.autoservizi.it &nbsp; Commenti Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all\u2019indirizzo IP del visitatore e la stringa dello user...","og_url":"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/","og_site_name":"Tempesta Autoservizi","article_publisher":"https:\/\/www.facebook.com\/autoservizitempesta\/","article_modified_time":"2024-12-20T08:01:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/","url":"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/","name":"Privacy Policy - Tempesta Autoservizi","isPartOf":{"@id":"https:\/\/www.autoservizitempesta.it\/#website"},"datePublished":"2024-12-20T07:36:54+00:00","dateModified":"2024-12-20T08:01:14+00:00","breadcrumb":{"@id":"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.autoservizitempesta.it\/privacy-policy-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.autoservizitempesta.it\/_wp_\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/www.autoservizitempesta.it\/#website","url":"https:\/\/www.autoservizitempesta.it\/","name":"Tempesta Autoservizi","description":"Viaggiare sereni","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autoservizitempesta.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/pages\/20332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/comments?post=20332"}],"version-history":[{"count":4,"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/pages\/20332\/revisions"}],"predecessor-version":[{"id":20336,"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/pages\/20332\/revisions\/20336"}],"wp:attachment":[{"href":"https:\/\/www.autoservizitempesta.it\/_wp_\/wp-json\/wp\/v2\/media?parent=20332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}